{"id":62590,"date":"2024-10-25T15:46:32","date_gmt":"2024-10-25T14:46:32","guid":{"rendered":"https:\/\/sas.unl.pt\/?post_type=product&#038;p=62590"},"modified":"2025-09-09T11:17:18","modified_gmt":"2025-09-09T10:17:18","slug":"aulas-de-salsa-avulsas","status":"publish","type":"product","link":"https:\/\/sas.unl.pt\/en\/produto\/aulas-de-salsa-avulsas\/","title":{"rendered":"Aulas de SALSA da NOVA (aulas avulsas)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p><strong>Aulas de SALSA CUBANA avulsas<\/strong><\/p>\n<p>2\u00aa feira &#8211; 19h00 (iniciados)<\/p>\n<p>5\u00aa feira &#8211; 19h00 (interm\u00e9dios)<\/p>\n","protected":false},"featured_media":58065,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[47],"product_tag":[],"class_list":["post-62590","product","type-product","status-publish","has-post-thumbnail","product_cat-desporto","first","instock","taxable","shipping-taxable","purchasable","product-type-variable"],"acf":[],"_links":{"self":[{"href":"https:\/\/sas.unl.pt\/en\/wp-json\/wp\/v2\/product\/62590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sas.unl.pt\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sas.unl.pt\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sas.unl.pt\/en\/wp-json\/wp\/v2\/media\/58065"}],"wp:attachment":[{"href":"https:\/\/sas.unl.pt\/en\/wp-json\/wp\/v2\/media?parent=62590"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/sas.unl.pt\/en\/wp-json\/wp\/v2\/product_brand?post=62590"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/sas.unl.pt\/en\/wp-json\/wp\/v2\/product_cat?post=62590"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/sas.unl.pt\/en\/wp-json\/wp\/v2\/product_tag?post=62590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}